{"id":55,"date":"2008-09-19T15:54:30","date_gmt":"2008-09-19T13:54:30","guid":{"rendered":"http:\/\/www.soeren-in-norwegen.net\/blog\/?p=55"},"modified":"2008-09-19T15:54:30","modified_gmt":"2008-09-19T13:54:30","slug":"typisk-tysk-typisk-norsk","status":"publish","type":"post","link":"http:\/\/www.soeren-in-norwegen.net\/blog\/2008\/09\/typisk-tysk-typisk-norsk\/","title":{"rendered":"typisk tysk &#8211; typisk norsk"},"content":{"rendered":"<p>Ich moechte mich gern beim Unisportclub in Magdeburg abmelden. Finde den dazu noetigen Zettel im Netz und da ist auch ein Feld fuer meine Mitgliedsnummer. Da ich die nicht im Kopf habe, schreibe ich die dort zustaendige Person diesbezueglich an. Zurueck kommt eine pampige Mail:<\/p>\n<blockquote><p><em>Wenn Sie das Formular richtig gelesen h\u00e4tten, h\u00e4tten Sie feststellen k\u00f6nnen,<br \/>\ndass die Mitgliedsnummer durch die Gesch\u00e4ftsstelle eingetragen wird.<\/em><\/p><\/blockquote>\n<p>in dem Formular steht NICHT, dass dieses Feld von der Geschaeftsstelle ausgefuellt wird! &#8230; naja &#8230; diese ganz besondere freundliche Hilfsbereitschaft ist eben typisch deutsch &#8230; aber vielleicht hatte diese Person ja auch nur einen schlechten Tag &#8230; blosz dann haben ganz schoen viele Deutsche ganz schoen viele schlechte Tage &#8230; alle die mal auf dem Arbeitsamt, waren wissen sicherlich wovon ich rede.<\/p>\n<p>Im Gegensatz dazu bin ich hier neulich auf der Suche nach einem Kindergartenplatz durch die Gegend gefahren und habe alle Kindergaerten abgeklappert. Leider alles voll und die &#8222;Bestellung&#8220; fuer einen Kindergartenplatz laeuft ueber die Kommune (wusste ich vorher, aber ich hatte gehofft, dass irgendwo was frei ist, ohne dass die Kommune das schon weiss) &#8230; dass Hugo hier noch seine Sozialversicherungsnummer braucht, ist die Kindergartenplatzbeschaffung doppelt kompliziert und da die im Formular benoetigt wird, hab ich das noch nicht ausgefuellt und los geschickt &#8230; bei der x-ten Kindergaertnerin dieses Problem geschildert und auf einmal meint sie zu mir<\/p>\n<blockquote><p><em> Wissen sie was, ich fuell das mal schnell fuer sie aus und schicke das dann an die Kommune.<\/em><\/p><\/blockquote>\n<p>Anscheinend gibt es Mittel und Wege das man schon auf die Wartelisten kommt und die Nummer nachreicht, was ich ja so erstmal nicht wissen konnte &#8230; Als ich laengst wieder an meinem Arbeitsplatz sass, ruft sie mich noch extra an um zu wissen, was denn unsere vier Wunschkindergaerten waeren &#8230; aber vielleicht hatte sie nur einen guten Tag &#8230;\u00a0blosz dann haben ganz schoen viele Norweger ganz schoen viele gute Tage &#8230; alle die mal mit Norwegern zu tun hatten, wissen sicherlich wovon ich rede.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich moechte mich gern beim Unisportclub in Magdeburg abmelden. Finde den dazu noetigen Zettel im Netz und da ist auch ein Feld fuer meine Mitgliedsnummer. Da ich die nicht im Kopf habe, schreibe ich die dort zustaendige Person diesbezueglich an. Zurueck kommt eine pampige Mail: Wenn Sie das Formular richtig gelesen h\u00e4tten, h\u00e4tten Sie feststellen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/posts\/55"}],"collection":[{"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":2,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/posts\/55\/revisions"}],"predecessor-version":[{"id":57,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/posts\/55\/revisions\/57"}],"wp:attachment":[{"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/media?parent=55"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/categories?post=55"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.soeren-in-norwegen.net\/blog\/wp-json\/wp\/v2\/tags?post=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}